{"id":3745,"date":"2022-09-27T08:54:31","date_gmt":"2022-09-27T08:54:31","guid":{"rendered":"https:\/\/cofradiamatrizandujar.org\/?p=3745"},"modified":"2022-09-27T08:54:33","modified_gmt":"2022-09-27T08:54:33","slug":"cartel-de-la-bajada-2022","status":"publish","type":"post","link":"https:\/\/cofradiamatrizandujar.org\/en\/cartel-de-la-bajada-2022","title":{"rendered":"Cartel de la Bajada 2022"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"526\" height=\"806\" src=\"https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2022\/09\/309496134_3307495379540242_2618726938581815855_n.jpg\" alt=\"\" class=\"wp-image-3746\" srcset=\"https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2022\/09\/309496134_3307495379540242_2618726938581815855_n.jpg 526w, https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2022\/09\/309496134_3307495379540242_2618726938581815855_n-196x300.jpg 196w, https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2022\/09\/309496134_3307495379540242_2618726938581815855_n-8x12.jpg 8w\" sizes=\"auto, (max-width: 526px) 100vw, 526px\" \/><\/figure>\n\n\n\n<p>Descripci\u00f3n de la obra seg\u00fan la autora:<\/p>\n\n\n\n<p>La obra est\u00e1 presidida como no, por la Virgen, centrada y elevada en la composici\u00f3n, que aparece con el terno que llevar\u00e1 en el Pontifical con el Nuncio del Papa, terno que fue realizado con oro de los cofrades y devotos.<\/p>\n\n\n\n<p>La <a><\/a>imagen a su vez aparece con su caracter\u00edstica r\u00e1faga, envuelta en vegetaci\u00f3n representando as\u00ed ese recorrido que har\u00e1 para bajar desde la Sierra, y escoltada por dos ramas de almendro, \u00e1rbol que por sus caracter\u00edsticas simboliza a Dios, as\u00ed como esas mariposas, met\u00e1fora de la conversi\u00f3n, resurrecci\u00f3n y transfiguraci\u00f3n cristianas.<\/p>\n\n\n\n<p>Quiero destacar la figura de Mar\u00eda como instrumento de Dios, Jes\u00fas vino a nosotros a trav\u00e9s de Ella, y as\u00ed llegamos nosotros a Cristo a trav\u00e9s de Mar\u00eda.<\/p>\n\n\n\n<p>Mar\u00eda que es rosa sin espinas, flor entre las flores que derramar\u00e1 su gracia entre nosotros con su presencia por las calles de And\u00fajar el pr\u00f3ximo mes de octubre.<\/p>\n\n\n\n<p>Representada en esos p\u00e9talos que sobre la ciudad caen como esa Rosa de Oro que en 2009, durante la celebraci\u00f3n de su A\u00f1o Jubilar, el Papa Benedicto XVI le concediese, \u201csingular privilegio\u201d con el que el Papa reconoce el Patronazgo sobre la Di\u00f3cesis de Ja\u00e9n, la profunda devoci\u00f3n con la que es venerada y la amplia Historia de su Romer\u00eda, la m\u00e1s antigua de Espa\u00f1a, y primera que la recibiera.<\/p>\n\n\n\n<p>A sus pies las banderas de la cofrad\u00eda que son una de las manifestaciones est\u00e9ticas cofrades m\u00e1s interesantes de Andaluc\u00eda, tanto por sus dimensiones como simbolog\u00eda. Banderas que siempre van en parejas y aportan movimiento y color, este \u00faltimo relacionado con el significado de la misma. Centrada en la parte inferior, una figura realiza el tremolar de la bandera, bailar la misma en c\u00edrculos, con la dificultad debido a su gran tama\u00f1o.<\/p>\n\n\n\n<p>Algo \u00fanico y caracter\u00edstico de la devoci\u00f3n de la Virgen de la Cabeza. Con todo esto, me parec\u00eda fundamental su aparici\u00f3n en el cartel.<\/p>\n\n\n\n<p>Todo lo completa la leyenda que hace anuncio de lo que va a suceder.<\/p>\n\n\n\n<p>Un cartel que adem\u00e1s de hacer catequesis transmita la alegr\u00eda y emotividad de los d\u00edas que vienen a trav\u00e9s del color.<\/p>\n\n\n\n<p>Con todo esto gracias Madre, gracias And\u00fajar.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.facebook.com\/hashtag\/and%C3%BAjarteespera?__eep__=6&amp;__cft__[0]=AZXEG3QI0t_iidQWnAw9AzYWgwMQWLpWRbBLWCywYgwzm3kHXv718YK6uSlMVhLikE5TKQGGVIEVBgFH2jodWOP9wVYFDtjQJ-x1ltIBV0yKJonwtyXkYIj3Fg1ix9klz9u2WMSR6HiPXtfasZC6KZsziK1OXkgLbGAhgCbJcues2UApgbGuD122ejlv64mqSma01hWpZS6jDoWYjXvhuX9K&amp;__tn__=*NK-R\">#And\u00fajarTeEspera<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descripci\u00f3n de la obra seg\u00fan la autora: La obra est\u00e1 presidida como no, por la Virgen, centrada y elevada en la composici\u00f3n, que aparece con el terno que llevar\u00e1 en el Pontifical con el Nuncio del Papa, terno que fue realizado con oro de los cofrades y devotos. La imagen a su vez aparece con [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3746,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[5],"tags":[],"class_list":{"0":"post-3745","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad","8":"entry"},"featured_image_src":"https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2022\/09\/309496134_3307495379540242_2618726938581815855_n-526x400.jpg","featured_image_src_square":"https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2022\/09\/309496134_3307495379540242_2618726938581815855_n-526x600.jpg","author_info":{"display_name":"Salva Marcos","author_link":"https:\/\/cofradiamatrizandujar.org\/en\/author\/salva"},"_links":{"self":[{"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/posts\/3745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/comments?post=3745"}],"version-history":[{"count":1,"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/posts\/3745\/revisions"}],"predecessor-version":[{"id":3747,"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/posts\/3745\/revisions\/3747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/media\/3746"}],"wp:attachment":[{"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/media?parent=3745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/categories?post=3745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/tags?post=3745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}