{"id":6202,"date":"2024-11-20T23:59:00","date_gmt":"2024-11-20T23:59:00","guid":{"rendered":"https:\/\/cofradiamatrizandujar.org\/?p=6202"},"modified":"2024-11-26T22:02:30","modified_gmt":"2024-11-26T22:02:30","slug":"donacion","status":"publish","type":"post","link":"https:\/\/cofradiamatrizandujar.org\/en\/donacion","title":{"rendered":"DONACI\u00d3N"},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"503\" src=\"https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467642066_973377891492243_6817340656169487758_n.jpg\" alt=\"\" class=\"wp-image-6203\" srcset=\"https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467642066_973377891492243_6817340656169487758_n.jpg 600w, https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467642066_973377891492243_6817340656169487758_n-300x252.jpg 300w, https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467642066_973377891492243_6817340656169487758_n-14x12.jpg 14w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p>En la tarde de hoy, 20 de noviembre de 2024, se ha procedido a la donaci\u00f3n de los \u00ab\ud835\uddd8\ud835\ude00\ud835\ude01\ud835\uddee\ud835\ude01\ud835\ude02\ud835\ude01\ud835\uddfc\ud835\ude00 \ud835\ude06 \ud835\udde5\ud835\uddf2\ud835\uddee\ud835\uddf9 \ud835\udde3\ud835\uddff\ud835\uddee\ud835\uddf4\ud835\uddfa\ud835\uddee\u0301\ud835\ude01\ud835\uddf6\ud835\uddf0\ud835\uddee \ud835\uddf1\ud835\uddf2 \ud835\uddf9\ud835\uddee \ud835\udde5\ud835\uddf2\ud835\uddee\ud835\uddf9 \ud835\uddd6\ud835\uddfc\ud835\uddf3\ud835\uddff\ud835\uddee\ud835\uddf1\ud835\uddf6\u0301\ud835\uddee \ud835\uddf1\ud835\uddf2 \ud835\udde1\ud835\ude02\ud835\uddf2\ud835\ude00\ud835\ude01\ud835\uddff\ud835\uddee \ud835\udde6\ud835\uddf2\ud835\uddfb\u0303\ud835\uddfc\ud835\uddff\ud835\uddee \ud835\uddf1\ud835\uddf2 \ud835\uddf9\ud835\uddee \ud835\uddd6\ud835\uddee\ud835\uddef\ud835\uddf2\ud835\ude07\ud835\uddee \ud835\udde3\ud835\uddee\ud835\ude01\ud835\uddff\ud835\uddfc\ud835\uddfb\ud835\uddee \ud835\uddf1\ud835\uddf2 \ud835\uddf2\ud835\ude00\ud835\ude01\ud835\uddee \ud835\uddf0\ud835\uddf6\ud835\ude02\ud835\uddf1\ud835\uddee\ud835\uddf1\u00bb, encuadernado y empastado, en la sede social de la Real e Ilustre Cofrad\u00eda Matriz.<\/p>\n\n\n\n<p>El presidente, D. Manuel Jos\u00e9 G\u00f3mez Mart\u00ednez, ha destacado en su intervenci\u00f3n que dicho libro fue encargado por el hermano <a><\/a>mayor en los a\u00f1os 1866 y 1867, D. Miguel Mart\u00ednez Utrera, teniendo como referencia en dicho libro el documento m\u00e1s antiguo que data de 1552, el cual tiene 472 a\u00f1os y que ve la luz gracias a la donaci\u00f3n a esta instituci\u00f3n de D. Mario Enrique Higuera Estudillo, quien al caer dicho documento en sus manos y contactar con varias personas, las mismas le indican que lo acerque a la Cofrad\u00eda Matriz.<\/p>\n\n\n\n<p>Como curiosidad a destacar, nos encontramos con documentos comprendidos entre los a\u00f1os 1800 y 1900. Los estatutos de 1800, escritos y bulas en lat\u00edn con su correspondiente traducci\u00f3n.<\/p>\n\n\n\n<p>A partir de este momento, la Real e Ilustre Cofrad\u00eda Matriz digitalizar\u00e1 dicho libro, con el fin de que todo el mundo pueda consultarlo a trav\u00e9s de la p\u00e1gina web. Adem\u00e1s, se estudiar\u00e1 la posibilidad de la restauraci\u00f3n del mismo.<\/p>\n\n\n\n<p>D. Manuel Jos\u00e9 ha querido hacer un llamamiento a todas aquellas personas que, con buena voluntad, puedan tener documentos o enseres de Nuestra Titular, para que se acerquen hasta la sede y nos hagan part\u00edcipes de lo que puedan tener, para as\u00ed poder compartirlo, bien mediante donaci\u00f3n o digitalizando dichos documentos, para el disfrute de todos aquellos fieles y devotos de la Sant\u00edsima Virgen de la Cabeza y de las generaciones venideras.<\/p>\n\n\n\n<p>El presidente de nuestra Cofrad\u00eda no ha querido olvidarse de los medios de comunicaci\u00f3n, agradeciendo el trato y la informaci\u00f3n para engrandecer a\u00fan mas esa devoci\u00f3n universal.<\/p>\n\n\n\n<p>Dicha rueda de prensa ha acabado con la r\u00fabrica de donaci\u00f3n entre la familia Higuera Alfonzo, el presidente y el secretario de la Real e Ilustre Cofrad\u00eda Matriz.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"788\" data-id=\"6205\" src=\"https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467312278_973377878158911_262406396330474839_n.jpg\" alt=\"\" class=\"wp-image-6205\" srcset=\"https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467312278_973377878158911_262406396330474839_n.jpg 940w, https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467312278_973377878158911_262406396330474839_n-300x251.jpg 300w, https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467312278_973377878158911_262406396330474839_n-768x644.jpg 768w, https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467312278_973377878158911_262406396330474839_n-14x12.jpg 14w\" sizes=\"auto, (max-width: 940px) 100vw, 940px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"503\" data-id=\"6204\" src=\"https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/466976526_973377864825579_677951440281978510_n.jpg\" alt=\"\" class=\"wp-image-6204\" srcset=\"https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/466976526_973377864825579_677951440281978510_n.jpg 600w, https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/466976526_973377864825579_677951440281978510_n-300x252.jpg 300w, https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/466976526_973377864825579_677951440281978510_n-14x12.jpg 14w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"503\" data-id=\"6206\" src=\"https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467816893_973377874825578_565456637791785776_n.jpg\" alt=\"\" class=\"wp-image-6206\" srcset=\"https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467816893_973377874825578_565456637791785776_n.jpg 600w, https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467816893_973377874825578_565456637791785776_n-300x252.jpg 300w, https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467816893_973377874825578_565456637791785776_n-14x12.jpg 14w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"503\" data-id=\"6209\" src=\"https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467642066_973377891492243_6817340656169487758_n-1.jpg\" alt=\"\" class=\"wp-image-6209\" srcset=\"https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467642066_973377891492243_6817340656169487758_n-1.jpg 600w, https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467642066_973377891492243_6817340656169487758_n-1-300x252.jpg 300w, https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467642066_973377891492243_6817340656169487758_n-1-14x12.jpg 14w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"503\" data-id=\"6207\" src=\"https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/466968307_973377854825580_2120040632686046213_n.jpg\" alt=\"\" class=\"wp-image-6207\" srcset=\"https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/466968307_973377854825580_2120040632686046213_n.jpg 600w, https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/466968307_973377854825580_2120040632686046213_n-300x252.jpg 300w, https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/466968307_973377854825580_2120040632686046213_n-14x12.jpg 14w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"503\" data-id=\"6208\" src=\"https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467641614_973377898158909_2791706670719612207_n.jpg\" alt=\"\" class=\"wp-image-6208\" srcset=\"https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467641614_973377898158909_2791706670719612207_n.jpg 600w, https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467641614_973377898158909_2791706670719612207_n-300x252.jpg 300w, https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467641614_973377898158909_2791706670719612207_n-14x12.jpg 14w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/figure>","protected":false},"excerpt":{"rendered":"<p>En la tarde de hoy, 20 de noviembre de 2024, se ha procedido a la donaci\u00f3n de los \u00ab\ud835\uddd8\ud835\ude00\ud835\ude01\ud835\uddee\ud835\ude01\ud835\ude02\ud835\ude01\ud835\uddfc\ud835\ude00 \ud835\ude06 \ud835\udde5\ud835\uddf2\ud835\uddee\ud835\uddf9 \ud835\udde3\ud835\uddff\ud835\uddee\ud835\uddf4\ud835\uddfa\ud835\uddee\u0301\ud835\ude01\ud835\uddf6\ud835\uddf0\ud835\uddee \ud835\uddf1\ud835\uddf2 \ud835\uddf9\ud835\uddee \ud835\udde5\ud835\uddf2\ud835\uddee\ud835\uddf9 \ud835\uddd6\ud835\uddfc\ud835\uddf3\ud835\uddff\ud835\uddee\ud835\uddf1\ud835\uddf6\u0301\ud835\uddee \ud835\uddf1\ud835\uddf2 \ud835\udde1\ud835\ude02\ud835\uddf2\ud835\ude00\ud835\ude01\ud835\uddff\ud835\uddee \ud835\udde6\ud835\uddf2\ud835\uddfb\u0303\ud835\uddfc\ud835\uddff\ud835\uddee \ud835\uddf1\ud835\uddf2 \ud835\uddf9\ud835\uddee \ud835\uddd6\ud835\uddee\ud835\uddef\ud835\uddf2\ud835\ude07\ud835\uddee \ud835\udde3\ud835\uddee\ud835\ude01\ud835\uddff\ud835\uddfc\ud835\uddfb\ud835\uddee \ud835\uddf1\ud835\uddf2 \ud835\uddf2\ud835\ude00\ud835\ude01\ud835\uddee \ud835\uddf0\ud835\uddf6\ud835\ude02\ud835\uddf1\ud835\uddee\ud835\uddf1\u00bb, encuadernado y empastado, en la sede social de la Real e Ilustre Cofrad\u00eda Matriz. El presidente, D. Manuel Jos\u00e9 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6209,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[5],"tags":[],"class_list":{"0":"post-6202","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad","8":"entry"},"featured_image_src":"https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467642066_973377891492243_6817340656169487758_n-1-600x400.jpg","featured_image_src_square":"https:\/\/cofradiamatrizandujar.org\/wp-content\/uploads\/2024\/11\/467642066_973377891492243_6817340656169487758_n-1.jpg","author_info":{"display_name":"Salva Marcos","author_link":"https:\/\/cofradiamatrizandujar.org\/en\/author\/salva"},"_links":{"self":[{"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/posts\/6202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/comments?post=6202"}],"version-history":[{"count":1,"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/posts\/6202\/revisions"}],"predecessor-version":[{"id":6210,"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/posts\/6202\/revisions\/6210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/media\/6209"}],"wp:attachment":[{"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/media?parent=6202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/categories?post=6202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cofradiamatrizandujar.org\/en\/wp-json\/wp\/v2\/tags?post=6202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}